{"id":486,"date":"2022-09-12T10:30:12","date_gmt":"2022-09-12T08:30:12","guid":{"rendered":"https:\/\/arthurmetz.com\/blog\/?page_id=486"},"modified":"2025-08-29T10:14:58","modified_gmt":"2025-08-29T08:14:58","slug":"notre-maison","status":"publish","type":"page","link":"https:\/\/arthurmetz.com\/blog\/notre-maison\/","title":{"rendered":"Notre Maison"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"486\" class=\"elementor elementor-486\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-461059b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"461059b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1a1ef9\" data-id=\"a1a1ef9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecaaff3 elementor-widget elementor-widget-heading\" data-id=\"ecaaff3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez la Maison Arthur Metz<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd8b8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bd8b8d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ef30f3\" data-id=\"1ef30f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30d35d7 elementor-widget elementor-widget-image\" data-id=\"30d35d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"960\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg\" class=\"attachment-full size-full wp-image-500\" alt=\"Maison Arthur Metz vignoble alsace\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg 1920w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace-300x150.jpg 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace-1024x512.jpg 1024w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace-768x384.jpg 768w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace-1536x768.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c011fea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c011fea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e919598\" data-id=\"e919598\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab3fcba H2 elementor-widget elementor-widget-heading\" data-id=\"ab3fcba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une histoire familiale ancr\u00e9e dans le terroir alsacien depuis 1904<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d27f042 elementor-widget elementor-widget-image\" data-id=\"d27f042\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"469\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/illustration-arthur-metz.jpg\" class=\"attachment-full size-full wp-image-510\" alt=\"Arthur Metz crayonn\u00e9\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/illustration-arthur-metz.jpg 800w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/illustration-arthur-metz-300x176.jpg 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/illustration-arthur-metz-768x450.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78527ad corps elementor-widget elementor-widget-text-editor\" data-id=\"78527ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>L\u2019histoire viticole de la famille Metz a d\u00e9but\u00e9 en 1904, dans la commune d\u2019Epfig, au c\u0153ur du vignoble alsacien. Vigneron dans ce village jusque dans les ann\u00e9es cinquante, puis producteur-n\u00e9gociant dans les c\u00e9l\u00e8bres chais de Bercy \u00e0 Paris, Monsieur Arthur Metz revient dans son village natal en 1972, pour y faire grandir l\u2019exploitation familiale. Il parvient alors \u00e0 la hisser parmi les plus importantes et prestigieuses d\u2019Alsace.<\/p><p>En 1991, la famille Metz c\u00e8de l\u2019affaire \u00e0 la famille Helfrich, qui perp\u00e9tue depuis l\u2019histoire et l\u2019essor de la maison viticole. En 1997, Arthur Metz s\u2019\u00e9toffe en s\u2019unissant avec la Maison familiale Laugel, une autre belle et grande exploitation, fond\u00e9e en 1895 et install\u00e9e \u00e0 Marlenheim. Construite autour d\u2019hommes et de femmes passionn\u00e9s, la Maison Arthur Metz dispose aujourd\u2019hui de plus de 1000 hectares de vignoble, int\u00e9gr\u00e9s en viticulture durable. Elle d\u00e9tient ainsi tous les atouts n\u00e9cessaires pour cr\u00e9er des vins et cr\u00e9mants respectueux de l&#8217;environnement, qui expriment leurs origines et leurs terroirs, en y associant la modernit\u00e9 des techniques viti-vinicoles. Ces derni\u00e8res d\u00e9cennies, la Maison a renforc\u00e9 son activit\u00e9 de vigneron-r\u00e9coltant et exploite d\u00e9sormais 85 hectares de vignoble en propri\u00e9t\u00e9, produisant directement 15 Grands Crus alsaciens, de diff\u00e9rents terroirs et c\u00e9pages.<\/p><p>Au fil du temps, Arthur Metz a su cr\u00e9er un lien fort et ind\u00e9fectible entre ses viticulteurs et ses consommateurs, amateurs de grands vins. La Maison sait se remettre en question chaque jour afin de s&#8217;am\u00e9liorer en permanence. Elle offre aujourd\u2019hui un panel exceptionnel de vins et de cr\u00e9mants, tous uniques et issus des terroirs les plus prestigieux, du nord au sud du vignoble alsacien. Le vin est notre passion, il est le fruit de notre travail et nous nous r\u00e9jouissons de pouvoir le partager avec vous.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1f620 H2 elementor-widget elementor-widget-heading\" data-id=\"1f1f620\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'humain au c\u0153ur de l'activit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc52dfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc52dfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb414e4\" data-id=\"cb414e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b79e12e elementor-widget elementor-widget-image\" data-id=\"b79e12e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/vendanges-manuelles-arthur-metz.jpg\" class=\"attachment-full size-full wp-image-559\" alt=\"\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/vendanges-manuelles-arthur-metz.jpg 600w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/vendanges-manuelles-arthur-metz-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10461df\" data-id=\"10461df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f056c48 e-transform elementor-widget elementor-widget-text-editor\" data-id=\"f056c48\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Depuis 1904 chez Arthur Metz, le savoir-faire se transmet, se partage et s\u2019am\u00e9liore sans cesse.<\/p><p>Parce que l\u2019humain est au c\u0153ur de notre m\u00e9tier, la Maison Arthur Metz est avant tout compos\u00e9e d\u2019\u00e9quipes de femmes et d\u2019hommes, experts de leurs m\u00e9tiers, passionn\u00e9s et engag\u00e9s. C&#8217;est gr\u00e2ce \u00e0 cette passion et cet engagement, que nous pouvons compter sur nos \u00e9quipes pour \u00e9laborer des vins et cr\u00e9mants toujours plus qualitatifs.<\/p><p>Nos collaborateurs repr\u00e9sentent la force vitale de l\u2019entreprise. Nous mettons tout en \u0153uvre pour am\u00e9liorer leur qualit\u00e9 de vie au travail et pr\u00e9server leur sant\u00e9 et s\u00e9curit\u00e9. L\u2019\u00e9panouissement de chacun, avec responsabilisation et implication, est au c\u0153ur de nos objectifs. Nous avons \u00e9galement \u00e0 c\u0153ur de former nos talents de demain et donnons ainsi la chance aux jeunes de se former dans de nombreux m\u00e9tiers au sein de notre entreprise.<\/p><p>Depuis des d\u00e9cennies, nous entretenons des relations durables avec nos apporteurs de raisins. Au-del\u00e0 du simple partenariat commercial, nous allons plus loin en les accompagnant au quotidien afin de maintenir un haut niveau d\u2019excellence de qualit\u00e9 des vignes et du vin.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34082bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34082bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5328a9d\" data-id=\"5328a9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be66640 H2 elementor-widget elementor-widget-heading\" data-id=\"be66640\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos propri\u00e9t\u00e9s<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-219448c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219448c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87be500\" data-id=\"87be500\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4106f75 elementor-widget elementor-widget-text-editor\" data-id=\"4106f75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>L\u2019ambition de la Maison Arthur Metz est de ma\u00eetriser l\u2019ensemble des processus complexes, de la culture de la vigne \u00e0 la logistique, en passant par la vinification et l\u2019embouteillage.&nbsp;<span style=\"font-size: 1rem\">Aujourd\u2019hui ancr\u00e9e dans le vignoble alsacien avec ses trois propri\u00e9t\u00e9s, la Maison Arthur Metz exploite 85 hectares de vignoble du nord au sud de l\u2019Alsace. Parmi ces 85 hectares, nous pouvons d\u00e9nombrer onze terroirs de grands crus prestigieux et de nombreux lieux dits de renom.&nbsp;<\/span><span style=\"font-size: 1rem\">Chacune de ces propri\u00e9t\u00e9s r\u00e9v\u00e8le une facette diff\u00e9rente de la diversit\u00e9 du terroir alsacien et offre des styles en harmonie avec les biotypes locaux.&nbsp;<\/span><span style=\"font-size: 1rem\">Notre savoir-faire au service du terroir. Nous travaillons nos vignes avec respect.&nbsp;<\/span><span style=\"font-size: 1rem\">De la taille de la vigne , au travail du sol, \u00e0 la gestion de l\u2019enherbement nos \u00e9quipes s\u2019adaptent et cr\u00e9ent une alchimie entre eux et les terroirs afin de vous offrir des vins \u00e0 la fois modernes, \u00e9l\u00e9gants et structur\u00e9s.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc2a991 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc2a991\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b2a93cd\" data-id=\"b2a93cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dfd57a elementor-widget elementor-widget-image\" data-id=\"3dfd57a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/elementor\/thumbs\/GCF_Klipfel_Romain_Guittet_78-q67pvju4qgipwgx88verj9kz971cqecptz8h7vc474.jpg\" title=\"GCF_Klipfel_Romain_Guittet_78\" alt=\"GCF_Klipfel_Romain_Guittet_78\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a00614 elementor-widget elementor-widget-text-editor\" data-id=\"7a00614\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La Maison Klipfel \u00e0 Barr, avec le Domaine Andr\u00e9 Lorentz constituent une maison et une cave familiale l\u00e9gendaire. Parmi les vignes travaill\u00e9es par la maison figurent les plus beaux terroirs d&#8217;Alsace depuis 1921, dont le grand cru Kastelberg \u00e0 Andlau ou encore le Kirchberg de Barr et son somptueux Clos Zisser. Cette propri\u00e9t\u00e9 fait partie des fleurons de l\u2019entreprise, \u00e0 travers ses trente hectares de vignoble et ses vins sign\u00e9s Famille Helfrich.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ddce18 elementor-widget elementor-widget-image\" data-id=\"1ddce18\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/elementor\/thumbs\/fh-logo-noir-q67pxk7ck80w5imbq9rvx1dp7yeoyqbfj78ah19dsg.png\" title=\"fh-logo noir\" alt=\"fh-logo noir\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e4cac2\" data-id=\"2e4cac2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aca41af elementor-widget elementor-widget-image\" data-id=\"aca41af\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/elementor\/thumbs\/colmar-vignoble-q67pvrcu94t0hcmb0yns37oo0a0afz6kj0gd230ytc.jpg\" title=\"colmar-vignoble\" alt=\"colmar-vignoble\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdc756 elementor-widget elementor-widget-text-editor\" data-id=\"0bdc756\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Fond\u00e9 en 1895, le Domaine Viticole de la Ville de Colmar se trouve en plein c\u0153ur de la capitale des vins d\u2019Alsace. Le Domaine exploite aujourd&#8217;hui vingt-huit hectares de vignoble dont le prestigieux vignoble des Hospices de Colmar. Parmi les vins du Domaine Viticole de la Ville de Colmar, vous pourrez d\u00e9couvrir de nombreux Grands Crus r\u00e9put\u00e9s comme le Grand Cru Pfersigberg, le Grand Cru Florimont ou le Grand Cru Hengst .<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eacc325\" data-id=\"eacc325\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3280b7b elementor-widget elementor-widget-image\" data-id=\"3280b7b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/elementor\/thumbs\/DUSENBACH-q67pwjjzy5vm5nhcgaul60khtu5auwaimw0xgdv5mo.jpg\" title=\"DUSENBACH\" alt=\"DUSENBACH\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea84c9a elementor-widget elementor-widget-text-editor\" data-id=\"ea84c9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le Domaine du Moulin du Dusenbach, vignoble historique d\u2019une ancienne filature, poss\u00e8de une histoire longue de trois si\u00e8cles.<br>Sur quinze communes r\u00e9parties entre Ribeauvill\u00e9 et Colmar, le long de la Route des Vins, le domaine s\u2019\u00e9tend aujourd\u2019hui sur vingt-sept hectares. Le Domaine du Moulin de Dusenbach valorise et travaille des parcelles de Grands Crus prestigieux&nbsp; comme le Kaefferkopf , le Schlossberg le Sporen ou le Schoenenbourg.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3db504 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3db504\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e26e453\" data-id=\"e26e453\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33b5148 H2 elementor-widget elementor-widget-heading\" data-id=\"33b5148\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos engagements<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f88a7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f88a7b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-947bec5\" data-id=\"947bec5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6ad9a6 elementor-widget elementor-widget-image\" data-id=\"a6ad9a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/enherbement-vignoble-alsace.jpg\" class=\"attachment-full size-full wp-image-590\" alt=\"enherbement vignoble alsacien\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/enherbement-vignoble-alsace.jpg 800w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/enherbement-vignoble-alsace-200x300.jpg 200w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/enherbement-vignoble-alsace-683x1024.jpg 683w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/enherbement-vignoble-alsace-768x1152.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33d2be6\" data-id=\"33d2be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-616bc70 elementor-widget elementor-widget-image\" data-id=\"616bc70\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/travail-de-la-vigne-main-alsace.jpg\" class=\"attachment-full size-full wp-image-549\" alt=\"vigne alsace\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/travail-de-la-vigne-main-alsace.jpg 600w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/travail-de-la-vigne-main-alsace-300x300.jpg 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/travail-de-la-vigne-main-alsace-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e91509 elementor-widget elementor-widget-image\" data-id=\"9e91509\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/tracteur-vignes-alsace.jpg\" class=\"attachment-full size-full wp-image-550\" alt=\"tracteur vignes alsace\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/tracteur-vignes-alsace.jpg 600w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/tracteur-vignes-alsace-300x300.jpg 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/tracteur-vignes-alsace-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e17cb6b\" data-id=\"e17cb6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bbe83d elementor-widget elementor-widget-text-editor\" data-id=\"0bbe83d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Arthur Metz est une Maison de Vins et Cr\u00e9mants d&#8217;Alsace engag\u00e9e et responsable. A chaque instant, nous sommes soucieux du bien-\u00eatre des hommes et des femmes qui \u0153uvrent pour notre Maison. De nos vignes \u00e0 la commercialisation de nos vins, nous travaillons quotidiennement avec des collaborateurs passionn\u00e9s pour obtenir le plus haut niveau de qualit\u00e9 dans nos diff\u00e9rents m\u00e9tiers. En parall\u00e8le, nous sommes engag\u00e9s dans une d\u00e9marche durable avec nos partenaires et veillons quotidiennement \u00e0 entretenir la qualit\u00e9 de la relation qui nous unit.<\/p><p>Nos terroirs, l&#8217;environnement ainsi que la pr\u00e9servation de la typicit\u00e9 de chaque appellation alsacienne sont au c\u0153ur de nos pr\u00e9occupations. Intimement convaincus que chaque parcelle poss\u00e8de une identit\u00e9 unique, nous portons une attention toute particuli\u00e8re \u00e0 pr\u00e9server ce caract\u00e8re en veillant \u00e0 l&#8217;\u00e9quation si particuli\u00e8re entre exposition, composition des sols et c\u00e9page plant\u00e9.\u00a0Nous travaillons de mani\u00e8re parcellaire, c\u2019est-\u00e0-dire en prenant soin individuellement des raisins issus de chaque parcelle, pour respecter et r\u00e9v\u00e9ler la richesse de chacune d\u2019entre elles.<\/p><p>Soucieux de ce que nous allons transmettre \u00e0 nos enfants, nous sommes engag\u00e9s dans une d\u00e9marche globale de bonnes pratiques viticoles. L\u2019ensemble du vignoble que nous exploitons est certifi\u00e9 HV3. Cette certification indique que nous sommes attach\u00e9s au respect de la biodiversit\u00e9, que nous sommes dans une d\u00e9marche de r\u00e9duction des intrants dans notre agriculture, mais \u00e9galement que nous travaillons \u00e0 pr\u00e9server et restaurer les ressources rares et pr\u00e9cieuses de notre plan\u00e8te. Dans la continuit\u00e9 de cette d\u00e9marche, nous avons fait un choix strat\u00e9gique pour l&#8217;avenir de notre vignoble. En effet, les propri\u00e9t\u00e9s de la Maison Arthur Metz sont en conversion vers une agriculture biologique. Le Clos Saint Jacques, situ\u00e9 parmi les parcelles du Domaine de Colmar, est un v\u00e9ritable laboratoire de la viticulture respectueuse de l\u2019environnement et de l\u2019homme. Situ\u00e9 proche des habitations, nous veillons \u00e0 ce que notre travail soit respectueux des hommes et des voisins \u00e0 plumes ou \u00e0 poils de la parcelle. Cet engagement d\u00e9coule d&#8217;une profonde conviction \u00e9cologique, mais il est \u00e9galement motiv\u00e9 par notre souhait de satisfaire nos clients et de maintenir une relation de confiance au fil des ann\u00e9es.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f27525 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f27525\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0768e9\" data-id=\"f0768e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf2a8af H2 elementor-widget elementor-widget-heading\" data-id=\"cf2a8af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une maison audacieuse<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-317176b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"317176b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3889a3e\" data-id=\"3889a3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b4fd0 elementor-widget elementor-widget-image\" data-id=\"41b4fd0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz-1024x1024.png\" class=\"attachment-large size-large wp-image-1204\" alt=\"\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz-1024x1024.png 1024w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz-300x300.png 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz-150x150.png 150w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz-768x768.png 768w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/spritz-arthur-metz.png 1200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a2716f\" data-id=\"1a2716f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d6ac1f elementor-widget elementor-widget-text-editor\" data-id=\"7d6ac1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Un savoir-faire, une vision !<\/p><p>Savoir se remettre en question, s\u2019adapter aux styles de consommation, utiliser des techniques viticoles innovantes, cr\u00e9er, voil\u00e0 ce que repr\u00e9sente la Maison Arthur Metz.\u00a0<\/p><p>Nous nous attelons \u00e0 incarner cet esprit. Inventer de nouvelles fa\u00e7ons de d\u00e9guster les vins et cr\u00e9mants d\u2019Alsace, tout en respectant la tradition r\u00e9gionale, permet \u00e0 notre soci\u00e9t\u00e9 de saisir les tendances du march\u00e9 et nous donne l\u2019occasion d\u2019en proposer de nouvelles !\u00a0<span style=\"font-size: 1rem\">Ainsi, la cuv\u00e9e ICE lanc\u00e9e en 2014, premier Cr\u00e9mant ICE d\u00e9gust\u00e9 sur gla\u00e7ons, r\u00e9volutionne et apporte aux amateurs un instant unique de consommation du cr\u00e9mant.\u00a0<\/span><\/p><p>E<span style=\"font-size: 1rem\">ntre tradition et modernit\u00e9, les \u00e9quipes de la Maison Arthur Metz \u00e9laborent chaque jour avec passion des cuv\u00e9es pour r\u00e9v\u00e9ler le meilleur de l\u2019Alsace, et concocter les prochaines tendances de demain !<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33b1217\" data-id=\"33b1217\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6ce805 elementor-widget elementor-widget-image\" data-id=\"f6ce805\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz.png\" class=\"attachment-full size-full wp-image-1203\" alt=\"\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz.png 1200w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz-300x300.png 300w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz-1024x1024.png 1024w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz-150x150.png 150w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/cremant-ice-rose-arthur-metz-768x768.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d623960 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d623960\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-351c72d\" data-id=\"351c72d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-892d08d H2 elementor-widget elementor-widget-heading\" data-id=\"892d08d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vinification : notre philosophie<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b6262b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6262b6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-839ef80\" data-id=\"839ef80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b5fd8e elementor-widget elementor-widget-text-editor\" data-id=\"7b5fd8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La particularit\u00e9 du style vinique et aromatique de notre Maison s&#8217;est construite au fil des d\u00e9cennies. Nous travaillons de fa\u00e7on parcellaire afin de pr\u00e9server l&#8217;identit\u00e9 de chaque terroir. Notre pr\u00e9f\u00e9rence va pour les vins secs mais nous ne sommes pas en reste sur les demi-secs et les liquoreux ! Nous faisons un travail rigoureux sur la fra\u00eecheur et l\u2019acidit\u00e9 de nos vins, notamment sur les vins moelleux et liquoreux afin de pr\u00e9server leur \u00e9quilibre.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b74568\" data-id=\"3b74568\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cedcdb8 elementor-widget elementor-widget-image\" data-id=\"cedcdb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Bouteilles-600-\u00d7-450-px.png\" class=\"attachment-large size-large wp-image-1214\" alt=\"Bouteille Alsace\" srcset=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Bouteilles-600-\u00d7-450-px.png 600w, https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Bouteilles-600-\u00d7-450-px-300x225.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez la Maison Arthur Metz Une histoire familiale ancr\u00e9e dans le terroir alsacien depuis 1904 L\u2019histoire viticole de la famille Metz a d\u00e9but\u00e9 en 1904, dans la commune d\u2019Epfig, au c\u0153ur du vignoble alsacien. Vigneron dans ce village jusque dans les ann\u00e9es cinquante, puis producteur-n\u00e9gociant dans les c\u00e9l\u00e8bres chais de Bercy \u00e0 Paris, Monsieur Arthur [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Notre Maison de Vins et Cr\u00e9mants d&#039;Alsace | Arthur Metz<\/title>\n<meta name=\"description\" content=\"\u27a4 L&#039;histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l&#039;\u00e9laboration de nos Vins et Cr\u00e9mants d&#039;Alsace.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arthurmetz.com\/blog\/notre-maison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre Maison de Vins et Cr\u00e9mants d&#039;Alsace | Arthur Metz\" \/>\n<meta property=\"og:description\" content=\"\u27a4 L&#039;histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l&#039;\u00e9laboration de nos Vins et Cr\u00e9mants d&#039;Alsace.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arthurmetz.com\/blog\/notre-maison\/\" \/>\n<meta property=\"og:site_name\" content=\"Arthur Metz\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T08:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arthurmetz.com\/blog\/notre-maison\/\",\"url\":\"https:\/\/arthurmetz.com\/blog\/notre-maison\/\",\"name\":\"Notre Maison de Vins et Cr\u00e9mants d'Alsace | Arthur Metz\",\"isPartOf\":{\"@id\":\"https:\/\/arthurmetz.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg\",\"datePublished\":\"2022-09-12T08:30:12+00:00\",\"dateModified\":\"2025-08-29T08:14:58+00:00\",\"description\":\"\u27a4 L'histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l'\u00e9laboration de nos Vins et Cr\u00e9mants d'Alsace.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arthurmetz.com\/blog\/notre-maison\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage\",\"url\":\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg\",\"contentUrl\":\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg\",\"width\":1920,\"height\":960,\"caption\":\"Maison Arthur Metz vignoble alsace\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arthurmetz.com\/blog\/#website\",\"url\":\"https:\/\/arthurmetz.com\/blog\/\",\"name\":\"Arthur Metz\",\"description\":\"Blog Arthur Metz\",\"publisher\":{\"@id\":\"https:\/\/arthurmetz.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arthurmetz.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arthurmetz.com\/blog\/#organization\",\"name\":\"Arthur Metz\",\"url\":\"https:\/\/arthurmetz.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arthurmetz.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Maison-Arthur-Metz-Logo-noir.png\",\"contentUrl\":\"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Maison-Arthur-Metz-Logo-noir.png\",\"width\":851,\"height\":241,\"caption\":\"Arthur Metz\"},\"image\":{\"@id\":\"https:\/\/arthurmetz.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre Maison de Vins et Cr\u00e9mants d'Alsace | Arthur Metz","description":"\u27a4 L'histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l'\u00e9laboration de nos Vins et Cr\u00e9mants d'Alsace.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arthurmetz.com\/blog\/notre-maison\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre Maison de Vins et Cr\u00e9mants d'Alsace | Arthur Metz","og_description":"\u27a4 L'histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l'\u00e9laboration de nos Vins et Cr\u00e9mants d'Alsace.","og_url":"https:\/\/arthurmetz.com\/blog\/notre-maison\/","og_site_name":"Arthur Metz","article_modified_time":"2025-08-29T08:14:58+00:00","og_image":[{"url":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arthurmetz.com\/blog\/notre-maison\/","url":"https:\/\/arthurmetz.com\/blog\/notre-maison\/","name":"Notre Maison de Vins et Cr\u00e9mants d'Alsace | Arthur Metz","isPartOf":{"@id":"https:\/\/arthurmetz.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage"},"image":{"@id":"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage"},"thumbnailUrl":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg","datePublished":"2022-09-12T08:30:12+00:00","dateModified":"2025-08-29T08:14:58+00:00","description":"\u27a4 L'histoire de notre Maison, nos propri\u00e9t\u00e9s, nos valeurs et nos engagements, au service de l'\u00e9laboration de nos Vins et Cr\u00e9mants d'Alsace.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arthurmetz.com\/blog\/notre-maison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arthurmetz.com\/blog\/notre-maison\/#primaryimage","url":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg","contentUrl":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/maison-arthur-metz-vignes-alsace.jpg","width":1920,"height":960,"caption":"Maison Arthur Metz vignoble alsace"},{"@type":"WebSite","@id":"https:\/\/arthurmetz.com\/blog\/#website","url":"https:\/\/arthurmetz.com\/blog\/","name":"Arthur Metz","description":"Blog Arthur Metz","publisher":{"@id":"https:\/\/arthurmetz.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arthurmetz.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arthurmetz.com\/blog\/#organization","name":"Arthur Metz","url":"https:\/\/arthurmetz.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arthurmetz.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Maison-Arthur-Metz-Logo-noir.png","contentUrl":"https:\/\/arthurmetz.com\/blog\/wp-content\/uploads\/2022\/09\/Maison-Arthur-Metz-Logo-noir.png","width":851,"height":241,"caption":"Arthur Metz"},"image":{"@id":"https:\/\/arthurmetz.com\/blog\/#\/schema\/logo\/image\/"}}]}},"lang":"fr","translations":{"fr":486},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/pages\/486"}],"collection":[{"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":324,"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/pages\/486\/revisions"}],"predecessor-version":[{"id":57752,"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/pages\/486\/revisions\/57752"}],"wp:attachment":[{"href":"https:\/\/arthurmetz.com\/blog\/wp-json\/wp\/v2\/media?parent=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}